{"id":65,"count":3,"description":"<h3>Qualit\u00e9 de l'air int\u00e9rieur<\/h3>\r\nNos \u00e9quipements ne servent pas seulement dans les espaces sensibles et st\u00e9riles. Nous proposons du mat\u00e9riel utile \u00e0 la mesure de la qualit\u00e9 de l\u2019air dans tous les espaces int\u00e9rieurs (lieux de travail, \u00e9coles, etc).\u00a0Ces mesures sont de plus en plus fr\u00e9quentes dans tous les types d\u2019\u00e9tablissements. Elles permettent de prot\u00e9ger la sant\u00e9 humaine, celle des usagers et celle des employ\u00e9s. La pollution et la pr\u00e9sence de certains micro-organismes dans l\u2019air que nous respirons influent en effet sur diverses pathologies comme les maladies cardio-vasculaires.\r\n<div class=\"show_more\">\r\n<div class=\"wpsm-content\">\r\n\r\nGr\u00e2ce \u00e0 nos appareils de mesure de Qualit\u00e9 de l'air int\u00e9rieur TSI, vous pouvez surveiller les taux de monoxyde de carbone (CO), de dioxyde de carbone (CO<sub>2<\/sub>), de temp\u00e9rature, d\u2019humidit\u00e9, de compos\u00e9s organiques volatils (COV) et de dioxyg\u00e8ne (O<sub>2<\/sub>).\r\n\r\n<\/div>\r\n<\/div>","link":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/","name":"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur","slug":"controle-de-la-qualite-et-de-la-contamination-de-lair-interieur","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contr\u00f4le de la qualit\u00e9 et de la contamination de l&#039;air int\u00e9rieur - Aerometrik<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre mat\u00e9riel utile contr\u00f4le de la qualit\u00e9 et de la contamination de l&#039;air int\u00e9rieur dans les espaces int\u00e9rieurs gr\u00e2ce aux appareils TSI et ATI\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contr\u00f4le de la qualit\u00e9 et de la contamination de l&#039;air int\u00e9rieur - Aerometrik\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre mat\u00e9riel utile contr\u00f4le de la qualit\u00e9 et de la contamination de l&#039;air int\u00e9rieur dans les espaces int\u00e9rieurs gr\u00e2ce aux appareils TSI et ATI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/\" \/>\n<meta property=\"og:site_name\" content=\"Aerometrik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/categorie-produit\\\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\\\/\",\"url\":\"https:\\\/\\\/www.aerometrik.com\\\/categorie-produit\\\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\\\/\",\"name\":\"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur - Aerometrik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/#website\"},\"description\":\"D\u00e9couvrez notre mat\u00e9riel utile contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur dans les espaces int\u00e9rieurs gr\u00e2ce aux appareils TSI et ATI\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/categorie-produit\\\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/categorie-produit\\\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.aerometrik.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/#website\",\"url\":\"https:\\\/\\\/www.aerometrik.com\\\/\",\"name\":\"Aerometrik\",\"description\":\"Solutions de ma\u00eetrise de la qualit\u00e9 de l&#039;air pour le secteur m\u00e9dical, et l&#039;industrie alimentaire et pharmaceutique\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aerometrik.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/#organization\",\"name\":\"Aerometrik\",\"url\":\"https:\\\/\\\/www.aerometrik.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aerometrik.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-aerometrik.svg\",\"contentUrl\":\"https:\\\/\\\/www.aerometrik.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-aerometrik.svg\",\"width\":212,\"height\":90,\"caption\":\"Aerometrik\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aerometrik.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur - Aerometrik","description":"D\u00e9couvrez notre mat\u00e9riel utile contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur dans les espaces int\u00e9rieurs gr\u00e2ce aux appareils TSI et ATI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/","og_locale":"en_US","og_type":"article","og_title":"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur - Aerometrik","og_description":"D\u00e9couvrez notre mat\u00e9riel utile contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur dans les espaces int\u00e9rieurs gr\u00e2ce aux appareils TSI et ATI","og_url":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/","og_site_name":"Aerometrik","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/","url":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/","name":"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur - Aerometrik","isPartOf":{"@id":"https:\/\/www.aerometrik.com\/#website"},"description":"D\u00e9couvrez notre mat\u00e9riel utile contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur dans les espaces int\u00e9rieurs gr\u00e2ce aux appareils TSI et ATI","breadcrumb":{"@id":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aerometrik.com\/categorie-produit\/controle-de-la-qualite-et-de-la-contamination-de-lair-interieur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.aerometrik.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Contr\u00f4le de la qualit\u00e9 et de la contamination de l'air int\u00e9rieur"}]},{"@type":"WebSite","@id":"https:\/\/www.aerometrik.com\/#website","url":"https:\/\/www.aerometrik.com\/","name":"Aerometrik","description":"Solutions de ma\u00eetrise de la qualit\u00e9 de l&#039;air pour le secteur m\u00e9dical, et l&#039;industrie alimentaire et pharmaceutique","publisher":{"@id":"https:\/\/www.aerometrik.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aerometrik.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.aerometrik.com\/#organization","name":"Aerometrik","url":"https:\/\/www.aerometrik.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aerometrik.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.aerometrik.com\/wp-content\/uploads\/2021\/08\/logo-aerometrik.svg","contentUrl":"https:\/\/www.aerometrik.com\/wp-content\/uploads\/2021\/08\/logo-aerometrik.svg","width":212,"height":90,"caption":"Aerometrik"},"image":{"@id":"https:\/\/www.aerometrik.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.aerometrik.com\/en\/wp-json\/wp\/v2\/product_cat\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aerometrik.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.aerometrik.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.aerometrik.com\/en\/wp-json\/wp\/v2\/product?product_cat=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}